{"id":1391,"date":"2023-11-10T02:15:21","date_gmt":"2023-11-10T02:15:21","guid":{"rendered":"https:\/\/wsfreespirit.com\/about-me\/"},"modified":"2026-05-10T00:57:03","modified_gmt":"2026-05-10T00:57:03","slug":"about-me","status":"publish","type":"page","link":"https:\/\/wsfreespirit.com\/it\/","title":{"rendered":"About"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.27.4&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row custom_padding_last_edited=&#8221;off|phone&#8221; _builder_version=&#8221;4.16&#8243; background_position=&#8221;bottom_center&#8221; custom_padding_tablet=&#8221;17vw||17vw||false&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Prata|500|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_font_size=&#8221;56px&#8221; header_2_line_height=&#8221;1.3em&#8221; transform_translate_linked=&#8221;off&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;26px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Walter E. Sanchez<\/h2>\n<h3>Artista, guida olistica e narratore spirituale.<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; max_width=&#8221;700px&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>La mia vita \u00e8 un viaggio alla ricerca di senso, attraversando paesaggi interiori ed esteriori. Tra montagne, selve e oceani imparo ad ascoltare il linguaggio profondo della natura. <\/p>\n<p>L&#8217;arte e la parola sono il mio ponte verso l&#8217;invisibile: i miei dipinti invitano al tatto e le mie fotografie catturano istanti che si percepiscono oltre il visibile. I miei documentari, d&#8217;altra parte, avvicinano lo spettatore a quelle esperienze che emergono quando si attraversa il velo invisibile verso il sacro. <\/p>\n<p>In cerimonie con i saggi scopro che la vera trasformazione nasce connettendosi con noi stessi e con l&#8217;essenza degli elementi. Questa connessione apre uno spazio dove l&#8217;ancestrale e il contemporaneo s&#8217;incontrano in uno stesso battito di vita. <\/p>\n<p>Da questa esperienza nascono i miei cinque libri \u2014 <strong>Terra, Acqua, Fuoco, Aria ed Etere<\/strong> \u2014 nei quali condivido insegnamenti e pratiche per accompagnare gli altri nel loro cammino verso l&#8217;equilibrio e l&#8217;autoconoscenza.<\/p>\n<p>Oggi, la mia missione \u00e8 continuare a creare, condividere e connettere, per accendere scintille di consapevolezza in ogni incontro e ricordare che ogni atto creativo \u00e8 anche un atto di trasformazione.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About&#8221; _builder_version=&#8221;4.27.4&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; max_width=&#8221;1280px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/Decoder-by-Walter-Sanchez-2014.-Photograph-18-x-24-inches.-e1405197287751.jpg&#8221; title_text=&#8221;Decoder-by-Walter-Sanchez-2014.-Photograph-18-x-24-inches.-e1405197287751 &#8221; _builder_version=&#8221;4.23.1&#8243; background_image=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-56.png&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;bottom_left&#8221; max_width_tablet=&#8221;560px&#8221; max_width_last_edited=&#8221;off|tablet&#8221; module_alignment=&#8221;right&#8221; custom_margin=&#8221;|-200px||&#8221; custom_margin_tablet=&#8221;|0px||&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;||40px|78px||&#8221; custom_padding_tablet=&#8221;40px|30px|0px|0px&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; background_last_edited=&#8221;on|desktop&#8221; background_position_tablet=&#8221;top_right&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;20px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;0px&#8221; box_shadow_color=&#8221;rgba(67,58,122,0.2)&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/h20aRRIBA-by-Walter_Sanchez-2014.-Photograph-18-x-24-inches.-e1405197341510.jpg&#8221; title_text=&#8221;h20aRRIBA-by-Walter_Sanchez-2014.-Photograph-18-x-24-inches.-e1405197341510 &#8221; _builder_version=&#8221;4.23.1&#8243; background_image=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-59.png&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_right&#8221; max_width=&#8221;560px&#8221; module_alignment=&#8221;right&#8221; custom_margin=&#8221;||30px&#8221; custom_padding=&#8221;40px|40px||&#8221; custom_padding_tablet=&#8221;|30px||&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|desktop&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;20px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;0px&#8221; box_shadow_color=&#8221;rgba(67,58,122,0.2)&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; link_font=&#8221;|600|||||||&#8221; link_text_color=&#8221;#545454&#8243; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.3em&#8221; background_color=&#8221;#ffffff&#8221; custom_margin=&#8221;150px||&#8221; custom_margin_tablet=&#8221;0px|||&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;-70px&#8221; box_shadow_vertical=&#8221;70px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;0px&#8221; box_shadow_color=&#8221;rgba(67,58,122,0.1)&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Carriera e Attivit\u00e0<\/h3>\n<p><span style=\"font-weight: 400;\">Sono il fondatore di <\/span><b>Service Hampton<\/b><span style=\"font-weight: 400;\"> a Sag Harbor, New York, dove ho servito la comunit\u00e0 degli Hamptons per oltre 25 anni.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ho anche creato <\/span><b>Share2Art.com<\/b><span style=\"font-weight: 400;\">una piattaforma che mette in contatto artisti di varie discipline e promuove la collaborazione creativa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Combino l&#8217;arte e la narrazione audiovisiva realizzando film biografici su <\/span><b>film biografici su artisti degli Hamptons<\/b><span style=\"font-weight: 400;\">integrando arte, storia e sensibilit\u00e0 in ogni progetto.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; max_width=&#8221;700px&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><strong>Approccio olistico<\/strong><\/h3>\n<div _ngcontent-ng-c3590532389=\"\" class=\"markdown markdown-main-panel stronger enable-updated-hr-color\" id=\"model-response-message-contentr_00cdb051dd1d6dc1\" dir=\"ltr\">\n<p><span style=\"font-weight: 400;\">Il mio approccio integra<\/span> <b>arte e guarigione<\/b><span style=\"font-weight: 400;\"> come percorsi complementari verso l&#8217;equilibrio interiore. Attraverso i miei dipinti \u2014 che esplorano il colore, la vibrazione e la consistenza \u2014 offro strumenti per risvegliare la sensibilit\u00e0 e aprire processi di trasformazione profonda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le mie opere sono progettate per<\/span> <b>essere toccate<\/b>: <span style=\"font-weight: 400;\">invitano a sentire con le mani ci\u00f2 che spesso non si vede con gli occhi. Questo aspetto tattile apre una nuova forma di percezione, pensata specialmente per<\/span> <b>persone non vedenti o con sensibilit\u00e0 speciale<\/b><span style=\"font-weight: 400;\">, e per chi cerca di connettersi con l&#8217;arte a partire da un&#8217;esperienza pi\u00f9 sensoriale e spirituale.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lavoro con <\/span><b>ciotole per il canto<\/b><span style=\"font-weight: 400;\">combinando suono e colore in un viaggio che armonizza corpo, mente e spirito.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Faccio anche <\/span><b>Cerimonie del tabacco e pulizie energetiche<\/b><span style=\"font-weight: 400;\">che mirano a liberare i blocchi, a ripristinare la chiarezza e a rinnovare l&#8217;energia vitale.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Queste esperienze si svolgono in un ambiente naturale, circondato dalla quiete delle foreste e dall&#8217;immensit\u00e0 dell&#8217;oceano. <\/span><b>la quiete delle foreste e l&#8217;immensit\u00e0 dell&#8217;oceano, dove il potere della Terra e dell&#8217;Acqua<\/b><span style=\"font-weight: 400;\">dove il potere della Terra e dell&#8217;Acqua amplifica la connessione e ci ricorda la nostra unione con il sacro.<\/span><\/p>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.3em&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Affari curatoriali<\/h3>\n<ul>\n<li>Lorem ipsum dolor<\/li>\n<li>Consectetuer adipiscing<\/li>\n<li>Aliquam tincidunt<\/li>\n<li>Vestibulum auctor<\/li>\n<li>Dapibus neque<\/li>\n<li>Nunc dignissim risus<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.3em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Relazioni pubbliche<\/h3>\n<ul>\n<li>Lorem ipsum dolor<\/li>\n<li>Consectetuer adipiscing<\/li>\n<li>Aliquam tincidunt<\/li>\n<li>Vestibulum auctor<\/li>\n<li>Dapibus neque<\/li>\n<li>Nunc dignissim risus<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.3em&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Amministrazioni<\/h3>\n<ul>\n<li>Lorem ipsum dolor<\/li>\n<li>Consectetuer adipiscing<\/li>\n<li>Aliquam tincidunt<\/li>\n<li>Vestibulum auctor<\/li>\n<li>Dapibus neque<\/li>\n<li>Nunc dignissim risus<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Features&#8221; _builder_version=&#8221;4.27.4&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row custom_padding_last_edited=&#8221;off|phone&#8221; _builder_version=&#8221;4.16&#8243; background_position=&#8221;bottom_center&#8221; custom_padding_tablet=&#8221;17vw||17vw||false&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;Prata|500|||||||&#8221; header_2_font_size=&#8221;56px&#8221; header_2_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_color=&#8221;rgba(0,0,0,0.35)&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;2em&#8221; transform_translate_linked=&#8221;off&#8221; text_orientation=&#8221;center&#8221; max_width=&#8221;700px&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; module_alignment=&#8221;center&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;26px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_3_font_size_phone=&#8221;10px&#8221; header_3_font_size_last_edited=&#8221;off|desktop&#8221; module_alignment_last_edited=&#8221;off|desktop&#8221; text_text_align=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Dai un&#8217;occhiata a<\/h3>\n<h2>Principali esposizioni di Walter <\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,1_5,1_5,1_5,1_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-29.jpg&#8221; align=&#8221;center&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; border_width_all=&#8221;16px&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_all_last_edited=&#8221;off|desktop&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;1px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.34)&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover=&#8221;#000000&#8243; border_width_all__hover=&#8221;20px&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.23.1&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>\u201cVersioni del Paradiso\u201d<\/h3>\n<p>Presso la Veterans&#8217; Memorial Hall di Southampton nel 2005<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art_gallery_04.jpg&#8221; align=&#8221;center&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; border_width_all=&#8221;16px&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_all_last_edited=&#8221;off|desktop&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;1px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.34)&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover=&#8221;#000000&#8243; border_width_all__hover=&#8221;20px&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.23.1&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>\u201cCostruzione di navi\/ponti\u201d<\/h3>\n<p>Presso Solar Contemporary Art and Design a East Hampton, New York nel 2007<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-30.jpg&#8221; align=&#8221;center&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; border_width_all=&#8221;16px&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_all_last_edited=&#8221;off|desktop&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;1px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.34)&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover=&#8221;#000000&#8243; border_width_all__hover=&#8221;20px&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.23.1&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>\u201cOpere senza titolo\u201d<\/h3>\n<p>Al 44\u00b0 Torneo Annuale di Primavera presso l&#8217;Ashawagh Hall nel 2011<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-35.jpg&#8221; align=&#8221;center&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; border_width_all=&#8221;16px&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_all_last_edited=&#8221;off|desktop&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;1px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.34)&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover=&#8221;#000000&#8243; border_width_all__hover=&#8221;20px&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.23.1&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>\u201cPeru-Iquitos\/Ayahuasca\u201d<\/h3>\n<p>Presso la Biblioteca Hampton a Bridgehampton nel 2012<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.23.1&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3> &#8220;Celebrando gli spiriti di: J. Steinbeck, E. Hemingway, T. Morrison e H. Miller&#8221; <\/h3>\n<p> Alla galleria BeUnico di Sag Harbor nel 2013[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,1_5,1_5,1_5,1_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-29.jpg&#8221; align=&#8221;center&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; border_width_all=&#8221;16px&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_all_last_edited=&#8221;off|desktop&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;1px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.34)&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover=&#8221;#000000&#8243; border_width_all__hover=&#8221;20px&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.23.1&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>\u201cThe Unconscious Code\u201d <\/h3>\n<p> Alla galleria BeUnico di Sag Harbor nel 2014[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art_gallery_04.jpg&#8221; align=&#8221;center&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; border_width_all=&#8221;16px&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_all_last_edited=&#8221;off|desktop&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;1px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.34)&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover=&#8221;#000000&#8243; border_width_all__hover=&#8221;20px&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.23.1&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>\u201cPuzzle Pieces\u201d<\/h3>\n<p> Alla galleria BeUnico di Sag Harbor nel 2015[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-30.jpg&#8221; align=&#8221;center&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; border_width_all=&#8221;16px&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_all_last_edited=&#8221;off|desktop&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;1px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.34)&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover=&#8221;#000000&#8243; border_width_all__hover=&#8221;20px&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.23.1&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>&#8220;Sum of Its Parts&#8221;<\/h3>\n<p>En Solar Contemporary Art and Design en East Hampton, Nueva York en 2015<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-35.jpg&#8221; align=&#8221;center&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; border_width_all=&#8221;16px&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_all_last_edited=&#8221;off|desktop&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;1px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.34)&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover=&#8221;#000000&#8243; border_width_all__hover=&#8221;20px&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Casa Roma Boutique Hotel<\/h3>\n<p>L&#8217;Unione, El Salvador nel 2023<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>&#8220;Artist Guestbook Canvas&#8221;<\/h3>\n<p> Sag Harbor NY USA nel 2025 [\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About&#8221; _builder_version=&#8221;4.27.4&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.16&#8243; max_width=&#8221;1280px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2025\/10\/unnamed-1.png&#8221; title_text=&#8221;unnamed (1)&#8221; _builder_version=&#8221;4.27.4&#8243; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_image=&#8221;https:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-56.png&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;bottom_left&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;560px&#8221; max_width_last_edited=&#8221;off|tablet&#8221; module_alignment=&#8221;right&#8221; custom_margin=&#8221;|-200px||&#8221; custom_margin_tablet=&#8221;|0px||&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;||40px|78px||&#8221; custom_padding_tablet=&#8221;40px|30px|0px|0px&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; background_last_edited=&#8221;on|desktop&#8221; background_position_tablet=&#8221;top_right&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;20px&#8221; header_3_line_height=&#8221;1.3em&#8221; background_color=&#8221;#ffffff&#8221; custom_margin=&#8221;114px|||||&#8221; custom_margin_tablet=&#8221;0px|||&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;40px|40px|40px|40px|true|true&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_horizontal=&#8221;-70px&#8221; box_shadow_vertical=&#8221;70px&#8221; box_shadow_blur=&#8221;80px&#8221; box_shadow_spread=&#8221;0px&#8221; box_shadow_color=&#8221;rgba(67,58,122,0.1)&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Progetto Share 2 Art: Interviste ad artisti all&#8217;inaugurazione di LTV-2022<\/h3>\n<p>Il progetto Share to Share, che sottolinea l&#8217;importanza della condivisione e della crescita nella vita. Per maggiori informazioni, visita il sito <a href=\"http:\/\/www.Share2Art.com\">www.Share2Art.com<\/a> <\/p>\n<h3>Walker &amp; Camino<\/h3>\n<p>Film: Children of the World<br \/>Longhouse Reserve East Hampton NY 2023 <a href=\"https:\/\/youtu.be\/7kvlsazLJfo?si=O7USaTnu7-DLXA_R\">(Guarda il video)<\/a><\/p>\n<h3>Oscar Molina<\/h3>\n<p><span style=\"font-weight: 400;\">Produzione di Walter E. Sanchez <a href=\"https:\/\/youtu.be\/xL2ZIXdt1vM\">(Guarda il video)<\/a><\/span><\/p>\n<h3>Arte dalle radici<\/h3>\n<p><span style=\"font-weight: 400;\">Produzione di Walter E. Sanchez <a href=\"https:\/\/www.youtube.com\/watch?v=58EVHFxgRY0\">(Guarda il video)<\/a><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Footer&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat-y&#8221; custom_padding=&#8221;0px|||||&#8221; disabled=&#8221;on&#8221; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; border_width_top=&#8221;2px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Direcci\u00f3n<\/h3>\n<p>Calle Divi 1234 #1000<br \/>San Francisco, CA 23514, EE.UU.<br \/>(246) 351-3613<\/p>\n<p>[\/et_pb_text][et_pb_button button_text=&#8221;Vis\u00edtanos&#8221; _builder_version=&#8221;4.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;rgba(0,0,0,0)&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_font=&#8221;|700|||||||&#8221; custom_margin_tablet=&#8221;0px|0px||&#8221; custom_margin_phone=&#8221;|0px||&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;6px|0px|6px|0px|true|true&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;1px&#8221; box_shadow_color=&#8221;#000000&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Horario de apertura<\/h3>\n<p>Lunes &#8211; Viernes: 10am &#8211; 5pm<br \/>Fines de semana: 10 h &#8211; 21 h<br \/>Festivos: Cerrado<\/p>\n<p>[\/et_pb_text][et_pb_button button_text=&#8221;Negozio&#8221; _builder_version=&#8221;4.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;rgba(0,0,0,0)&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_font=&#8221;|700|||||||&#8221; custom_margin_tablet=&#8221;0px|0px||&#8221; custom_margin_phone=&#8221;|0px||&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;6px|0px|6px|0px|true|true&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;1px&#8221; box_shadow_color=&#8221;#000000&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_button button_text=&#8221;Eventos de hoy&#8221; _builder_version=&#8221;4.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;rgba(0,0,0,0)&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_font=&#8221;|700|||||||&#8221; custom_margin_tablet=&#8221;0px|0px||&#8221; custom_margin_phone=&#8221;|0px||&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;6px|0px|6px|0px|true|true&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;1px&#8221; box_shadow_color=&#8221;#000000&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_2_font=&#8221;||||||||&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>vai avanti<\/h3>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;-20px|||-10px&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;-20px||&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; filter_invert=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; icon_color__hover=&#8221;#e02b20&#8243;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;twitter&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]twitter[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;google-plus&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]google-plus[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on||||&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Suscr\u00edbete<\/h3>\n<p>[\/et_pb_text][et_pb_signup mailchimp_list=&#8221;SlavaET|11a914d1cc&#8221; first_name_field=&#8221;off&#8221; last_name_field=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; form_field_background_color=&#8221;#f3f3f4&#8243; form_field_custom_padding=&#8221;12px||12px||true&#8221; header_font=&#8221;|||on|||||&#8221; header_font_size=&#8221;14px&#8221; header_letter_spacing=&#8221;5px&#8221; header_line_height=&#8221;1.8em&#8221; form_field_font=&#8221;||||||||&#8221; form_field_font_size=&#8221;14px&#8221; use_background_color=&#8221;off&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#ffffff&#8221; button_bg_color=&#8221;#000000&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;0px&#8221; button_font=&#8221;|700|||||||&#8221; button_custom_padding=&#8221;12px||12px||true&#8221; background_layout=&#8221;light&#8221; custom_margin=&#8221;-39px||&#8221; border_radii_fields=&#8221;on|0px|0px|0px|0px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_signup][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Walter E. Sanchez Artista, guida olistica e narratore spirituale.La mia vita \u00e8 un viaggio alla ricerca di senso, attraversando paesaggi interiori ed esteriori. Tra montagne, selve e oceani imparo ad ascoltare il linguaggio profondo della natura. L&#8217;arte e la parola sono il mio ponte verso l&#8217;invisibile: i miei dipinti invitano al tatto e le mie [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1391","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About - Artwes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wsfreespirit.com\/it\/about-me\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About - Artwes\" \/>\n<meta property=\"og:description\" content=\"Walter E. Sanchez Artista, guida olistica e narratore spirituale.La mia vita \u00e8 un viaggio alla ricerca di senso, attraversando paesaggi interiori ed esteriori. Tra montagne, selve e oceani imparo ad ascoltare il linguaggio profondo della natura. L&#039;arte e la parola sono il mio ponte verso l&#039;invisibile: i miei dipinti invitano al tatto e le mie [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wsfreespirit.com\/it\/about-me\/\" \/>\n<meta property=\"og:site_name\" content=\"Artwes\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-10T00:57:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wsfreespirit.com\\\/it\\\/about-me\\\/\",\"url\":\"https:\\\/\\\/wsfreespirit.com\\\/it\\\/about-me\\\/\",\"name\":\"About - Artwes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wsfreespirit.com\\\/#website\"},\"datePublished\":\"2023-11-10T02:15:21+00:00\",\"dateModified\":\"2026-05-10T00:57:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wsfreespirit.com\\\/it\\\/about-me\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wsfreespirit.com\\\/it\\\/about-me\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wsfreespirit.com\\\/it\\\/about-me\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wsfreespirit.com\\\/it\\\/about-me\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wsfreespirit.com\\\/#website\",\"url\":\"https:\\\/\\\/wsfreespirit.com\\\/\",\"name\":\"Artwes\",\"description\":\"Artist Page By Walter E. Sanchez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wsfreespirit.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About - Artwes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wsfreespirit.com\/it\/about-me\/","og_locale":"it_IT","og_type":"article","og_title":"About - Artwes","og_description":"Walter E. Sanchez Artista, guida olistica e narratore spirituale.La mia vita \u00e8 un viaggio alla ricerca di senso, attraversando paesaggi interiori ed esteriori. Tra montagne, selve e oceani imparo ad ascoltare il linguaggio profondo della natura. L'arte e la parola sono il mio ponte verso l'invisibile: i miei dipinti invitano al tatto e le mie [&hellip;]","og_url":"https:\/\/wsfreespirit.com\/it\/about-me\/","og_site_name":"Artwes","article_modified_time":"2026-05-10T00:57:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wsfreespirit.com\/it\/about-me\/","url":"https:\/\/wsfreespirit.com\/it\/about-me\/","name":"About - Artwes","isPartOf":{"@id":"https:\/\/wsfreespirit.com\/#website"},"datePublished":"2023-11-10T02:15:21+00:00","dateModified":"2026-05-10T00:57:03+00:00","breadcrumb":{"@id":"https:\/\/wsfreespirit.com\/it\/about-me\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wsfreespirit.com\/it\/about-me\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wsfreespirit.com\/it\/about-me\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wsfreespirit.com\/it\/about-me\/"},{"@type":"ListItem","position":2,"name":"About"}]},{"@type":"WebSite","@id":"https:\/\/wsfreespirit.com\/#website","url":"https:\/\/wsfreespirit.com\/","name":"Artwes","description":"Artist Page By Walter E. Sanchez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wsfreespirit.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wsfreespirit.com\/it\/wp-json\/wp\/v2\/pages\/1391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsfreespirit.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wsfreespirit.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wsfreespirit.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wsfreespirit.com\/it\/wp-json\/wp\/v2\/comments?post=1391"}],"version-history":[{"count":4,"href":"https:\/\/wsfreespirit.com\/it\/wp-json\/wp\/v2\/pages\/1391\/revisions"}],"predecessor-version":[{"id":1490,"href":"https:\/\/wsfreespirit.com\/it\/wp-json\/wp\/v2\/pages\/1391\/revisions\/1490"}],"wp:attachment":[{"href":"https:\/\/wsfreespirit.com\/it\/wp-json\/wp\/v2\/media?parent=1391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}