{"id":1336,"date":"2023-11-21T00:14:59","date_gmt":"2023-11-21T00:14:59","guid":{"rendered":"https:\/\/wsfreespirit.com\/artist-statement\/"},"modified":"2026-02-17T19:16:09","modified_gmt":"2026-02-17T19:16:09","slug":"artist-statement","status":"publish","type":"page","link":"https:\/\/wsfreespirit.com\/fr\/artist-statement\/","title":{"rendered":"D\u00e9claration de l&rsquo;artiste"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbHeader\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; background_color=\u00a0\u00bb#efeef3&Prime; background_enable_image=\u00a0\u00bboff\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row custom_padding_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_position=\u00a0\u00bbbottom_center\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb17vw||17vw||false\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font_size=\u00a0\u00bb32px\u00a0\u00bb header_2_font=\u00a0\u00bbPrata|500|||||||\u00a0\u00bb header_2_text_align=\u00a0\u00bbleft\u00a0\u00bb header_2_font_size=\u00a0\u00bb45px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.3em\u00a0\u00bb transform_translate_linked=\u00a0\u00bboff\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb max_width_tablet=\u00a0\u00bb70%\u00a0\u00bb max_width_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb26px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2>D\u00e9claration de l&rsquo;artiste<\/h2>\n<h2>Walter E. Sanchez<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb max_width=\u00a0\u00bb700px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>Je consacre ma vie \u00e0<strong> cultiver ma sensibilit\u00e9, <\/strong>\u00e0 apprendre \u00e0 <strong>percevoir le subtil, <\/strong>\u00e0 <strong>\u00e9couter le profond<\/strong> et \u00e0 <strong>ressentir ce qui se cache au-del\u00e0 des formes.<\/strong> Mon art est le reflet de ce cheminement : un espace o\u00f9 <strong>la couleur, la texture et la vibration<\/strong> se transforment en langage.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbAbout\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; background_color=\u00a0\u00bb#efeef3&Prime; background_enable_image=\u00a0\u00bboff\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_padding=\u00a0\u00bb2px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; max_width=\u00a0\u00bb1280px\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb20px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb background_color=\u00a0\u00bb#ffffff\u00a0\u00bb custom_margin=\u00a0\u00bb-1px|||||\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px|||\u00a0\u00bb custom_margin_phone=\u00a0\u00bb\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb custom_padding=\u00a0\u00bb40px|40px|40px|40px|true|true\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; header_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_font_size_phone=\u00a0\u00bb\u00a0\u00bb header_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset3&Prime; box_shadow_horizontal=\u00a0\u00bb-70px\u00a0\u00bb box_shadow_vertical=\u00a0\u00bb70px\u00a0\u00bb box_shadow_blur=\u00a0\u00bb80px\u00a0\u00bb box_shadow_spread=\u00a0\u00bb0px\u00a0\u00bb box_shadow_color=\u00a0\u00bbrgba(67,58,122,0.1)\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>Chaque \u0153uvre na\u00eet comme un <strong>pont entre le visible et l&rsquo;invisible,<\/strong> entre l&rsquo;intime et l&rsquo;universel. Je peins et photographie non seulement pour montrer des images, mais aussi pour inviter le spectateur \u00e0 <strong>toucher, percevoir et r\u00e9veiller des souvenirs profonds.<\/strong><br \/>Je crois que l&rsquo;art est un <strong>vecteur de transformation.<\/strong> De m\u00eame qu&rsquo;il m&rsquo;a permis de gu\u00e9rir et de d\u00e9couvrir de nouvelles facettes de moi-m\u00eame, j&rsquo;esp\u00e8re que mes cr\u00e9ations ouvriront \u00e9galement un espace de d\u00e9couverte int\u00e9rieure chez les autres.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb44px|auto||auto||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb max_width=\u00a0\u00bb700px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h2>Ma d\u00e9claration est simple :<\/h2>\n<p>Vivre l&rsquo;art comme un chemin vers la prise de conscience et le partager comme une \u00e9tincelle qui suscite de nouvelles perspectives, de nouvelles questions et de nouvelles fa\u00e7ons d&rsquo;habiter le monde.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb admin_label=\u00a0\u00bbFeatures\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; background_enable_image=\u00a0\u00bboff\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row custom_padding_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_position=\u00a0\u00bbbottom_center\u00a0\u00bb custom_padding_tablet=\u00a0\u00bb17vw||17vw||false\u00a0\u00bb use_custom_width=\u00a0\u00bbon\u00a0\u00bb width_unit=\u00a0\u00bboff\u00a0\u00bb custom_width_percent=\u00a0\u00bb100%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_2_font=\u00a0\u00bbPrata|500|||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb56px\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_text_color=\u00a0\u00bbrgba(0,0,0,0.35)\u00a0\u00bb header_3_font_size=\u00a0\u00bb12px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb5px\u00a0\u00bb header_3_line_height=\u00a0\u00bb2em\u00a0\u00bb transform_translate_linked=\u00a0\u00bboff\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb max_width=\u00a0\u00bb700px\u00a0\u00bb max_width_tablet=\u00a0\u00bb70%\u00a0\u00bb max_width_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb header_2_font_size_tablet=\u00a0\u00bb40px\u00a0\u00bb header_2_font_size_phone=\u00a0\u00bb26px\u00a0\u00bb header_2_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb10px\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb module_alignment_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb text_text_align=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Jetez un coup d&rsquo;\u0153il \u00e0<\/h3>\n<h2>Les principales expositions de Walter ont eu lieu \u00e0 New York et au Salvador.<br \/>\n<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_5,1_5,1_5,1_5,1_5&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-29.jpg\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; border_width_all=\u00a0\u00bb16px\u00a0\u00bb border_color_all=\u00a0\u00bb#ffffff\u00a0\u00bb border_width_all_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset4&Prime; box_shadow_horizontal=\u00a0\u00bb0px\u00a0\u00bb box_shadow_vertical=\u00a0\u00bb0px\u00a0\u00bb box_shadow_spread=\u00a0\u00bb1px\u00a0\u00bb box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.34)\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bb#000000&Prime; border_width_all__hover=\u00a0\u00bb20px\u00a0\u00bb][\/et_pb_image][et_pb_text ul_position=\u00a0\u00bbinside\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb ul_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb text_text_align=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>\u00ab Versions du Paradis \u00bb<\/h3>\n<p>Au M\u00e9morial des V\u00e9t\u00e9rans de Southampton en 2005<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art_gallery_04.jpg\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; border_width_all=\u00a0\u00bb16px\u00a0\u00bb border_color_all=\u00a0\u00bb#ffffff\u00a0\u00bb border_width_all_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset4&Prime; box_shadow_horizontal=\u00a0\u00bb0px\u00a0\u00bb box_shadow_vertical=\u00a0\u00bb0px\u00a0\u00bb box_shadow_spread=\u00a0\u00bb1px\u00a0\u00bb box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.34)\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bb#000000&Prime; border_width_all__hover=\u00a0\u00bb20px\u00a0\u00bb][\/et_pb_image][et_pb_text ul_position=\u00a0\u00bbinside\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb ul_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb text_text_align=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>\u00ab Construcci\u00f3n de Barcos\/Puentes \u00bb<\/h3>\n<p>Chez Solar Contemporary Art and Design \u00e0 East Hampton, New York, en 2007<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-30.jpg\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; border_width_all=\u00a0\u00bb16px\u00a0\u00bb border_color_all=\u00a0\u00bb#ffffff\u00a0\u00bb border_width_all_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset4&Prime; box_shadow_horizontal=\u00a0\u00bb0px\u00a0\u00bb box_shadow_vertical=\u00a0\u00bb0px\u00a0\u00bb box_shadow_spread=\u00a0\u00bb1px\u00a0\u00bb box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.34)\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bb#000000&Prime; border_width_all__hover=\u00a0\u00bb20px\u00a0\u00bb][\/et_pb_image][et_pb_text ul_position=\u00a0\u00bbinside\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb ul_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb text_text_align=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>\u00ab \u0152uvres sans titre \u00bb<\/h3>\n<p>Lors du 44e tournoi annuel de printemps \u00e0 Ashawagh Hall en 2011<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-35.jpg\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; border_width_all=\u00a0\u00bb16px\u00a0\u00bb border_color_all=\u00a0\u00bb#ffffff\u00a0\u00bb border_width_all_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset4&Prime; box_shadow_horizontal=\u00a0\u00bb0px\u00a0\u00bb box_shadow_vertical=\u00a0\u00bb0px\u00a0\u00bb box_shadow_spread=\u00a0\u00bb1px\u00a0\u00bb box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.34)\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bb#000000&Prime; border_width_all__hover=\u00a0\u00bb20px\u00a0\u00bb][\/et_pb_image][et_pb_text ul_position=\u00a0\u00bbinside\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb ul_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb text_text_align=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>\u00ab Peru-Iquitos\/Ayahuasca \u00bb<\/h3>\n<p>\u00c0 la biblioth\u00e8que Hampton de Bridgehampton en 2012<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text ul_position=\u00a0\u00bbinside\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb ul_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb text_text_align=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3> \u00ab Celebrating the Spirits of: J. Steinbeck, E. Hemingway, T. Morrison, and H. Miller \u00bb <\/h3>\n<p> \u00c0 la galerie BeUnico de Sag Harbor en 2013[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_5,1_5,1_5,1_5,1_5&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-29.jpg\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; border_width_all=\u00a0\u00bb16px\u00a0\u00bb border_color_all=\u00a0\u00bb#ffffff\u00a0\u00bb border_width_all_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset4&Prime; box_shadow_horizontal=\u00a0\u00bb0px\u00a0\u00bb box_shadow_vertical=\u00a0\u00bb0px\u00a0\u00bb box_shadow_spread=\u00a0\u00bb1px\u00a0\u00bb box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.34)\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bb#000000&Prime; border_width_all__hover=\u00a0\u00bb20px\u00a0\u00bb][\/et_pb_image][et_pb_text ul_position=\u00a0\u00bbinside\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb ul_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb text_text_align=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>\u00ab The Unconscious Code\u00bb <\/h3>\n<p> \u00c0 la galerie BeUnico de Sag Harbor en 2014[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art_gallery_04.jpg\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; border_width_all=\u00a0\u00bb16px\u00a0\u00bb border_color_all=\u00a0\u00bb#ffffff\u00a0\u00bb border_width_all_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset4&Prime; box_shadow_horizontal=\u00a0\u00bb0px\u00a0\u00bb box_shadow_vertical=\u00a0\u00bb0px\u00a0\u00bb box_shadow_spread=\u00a0\u00bb1px\u00a0\u00bb box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.34)\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bb#000000&Prime; border_width_all__hover=\u00a0\u00bb20px\u00a0\u00bb][\/et_pb_image][et_pb_text ul_position=\u00a0\u00bbinside\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb ul_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb text_text_align=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>\u00ab Puzzle Pieces \u00bb<\/h3>\n<p> \u00c0 la galerie BeUnico de Sag Harbor en 2015[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-30.jpg\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; border_width_all=\u00a0\u00bb16px\u00a0\u00bb border_color_all=\u00a0\u00bb#ffffff\u00a0\u00bb border_width_all_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset4&Prime; box_shadow_horizontal=\u00a0\u00bb0px\u00a0\u00bb box_shadow_vertical=\u00a0\u00bb0px\u00a0\u00bb box_shadow_spread=\u00a0\u00bb1px\u00a0\u00bb box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.34)\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bb#000000&Prime; border_width_all__hover=\u00a0\u00bb20px\u00a0\u00bb][\/et_pb_image][et_pb_text ul_position=\u00a0\u00bbinside\u00a0\u00bb _builder_version=\u00a0\u00bb4.23.1&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb ul_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb text_text_align=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>\u00ab Sum of Its Parts \u00bb<\/h3>\n<p>Chez Solar Contemporary Art and Design \u00e0 East Hampton, New York, en 2015<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/wsfreespirit.com\/wp-content\/uploads\/2023\/11\/art-gallery-35.jpg\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; border_width_all=\u00a0\u00bb16px\u00a0\u00bb border_color_all=\u00a0\u00bb#ffffff\u00a0\u00bb border_width_all_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset4&Prime; box_shadow_horizontal=\u00a0\u00bb0px\u00a0\u00bb box_shadow_vertical=\u00a0\u00bb0px\u00a0\u00bb box_shadow_spread=\u00a0\u00bb1px\u00a0\u00bb box_shadow_color=\u00a0\u00bbrgba(0,0,0,0.34)\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb box_shadow_color__hover=\u00a0\u00bb#000000&Prime; border_width_all__hover=\u00a0\u00bb20px\u00a0\u00bb][\/et_pb_image][et_pb_text ul_position=\u00a0\u00bbinside\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb ul_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb text_text_align=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>H\u00f4tel boutique Casa Roma<\/h3>\n<p>L&rsquo;Union, Salvador en 2023<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_5&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text ul_position=\u00a0\u00bbinside\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb ul_font=\u00a0\u00bb||||||||\u00a0\u00bb header_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_font_size=\u00a0\u00bb20px\u00a0\u00bb header_line_height=\u00a0\u00bb1.3em\u00a0\u00bb header_3_font=\u00a0\u00bb|700|||||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb14px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.3em\u00a0\u00bb text_orientation=\u00a0\u00bbcenter\u00a0\u00bb text_text_align=\u00a0\u00bbcenter\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>\u00ab Artist Guestbook Canvas \u00bb<\/h3>\n<p> Sag Harbor, New York, \u00c9tats-Unis, en 2025 [\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb admin_label=\u00a0\u00bbFooter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat-y\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb saved_tabs=\u00a0\u00bball\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb1_4,1_4,1_4,1_4&Prime; use_custom_gutter=\u00a0\u00bbon\u00a0\u00bb gutter_width=\u00a0\u00bb2&Prime; _builder_version=\u00a0\u00bb4.16&Prime; border_width_top=\u00a0\u00bb2px\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb12px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb link_font=\u00a0\u00bb||||on||||\u00a0\u00bb link_text_color=\u00a0\u00bb#666666&Prime; header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_text_align=\u00a0\u00bbleft\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb12px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb5px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.8em\u00a0\u00bb max_width_tablet=\u00a0\u00bb70%\u00a0\u00bb max_width_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Direcci\u00f3n<\/h3>\n<p>Calle Divi 1234 #1000<br \/>San Francisco, CA 23514, EE.UU.<br \/>(246) 351-3613<\/p>\n<p>[\/et_pb_text][et_pb_button button_text=\u00a0\u00bbVis\u00edtanos\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_bg_color=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_font=\u00a0\u00bb|700|||||||\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px|0px||\u00a0\u00bb custom_margin_phone=\u00a0\u00bb|0px||\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb custom_padding=\u00a0\u00bb6px|0px|6px|0px|true|true\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset4&Prime; box_shadow_horizontal=\u00a0\u00bb0px\u00a0\u00bb box_shadow_vertical=\u00a0\u00bb1px\u00a0\u00bb box_shadow_color=\u00a0\u00bb#000000&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb12px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb link_font=\u00a0\u00bb||||on||||\u00a0\u00bb link_text_color=\u00a0\u00bb#666666&Prime; header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_text_align=\u00a0\u00bbleft\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb12px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb5px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.8em\u00a0\u00bb max_width_tablet=\u00a0\u00bb70%\u00a0\u00bb max_width_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Horaires d&rsquo;ouverture<\/h3>\n<p>Du lundi au vendredi : 10h00 &#8211; 17h00<br \/>Week-ends : 10h00 &#8211; 21h00<br \/>Jours f\u00e9ri\u00e9s : Ferm\u00e9<\/p>\n<p>[\/et_pb_text][et_pb_button button_text=\u00a0\u00bbMagasin\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_bg_color=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_font=\u00a0\u00bb|700|||||||\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px|0px||\u00a0\u00bb custom_margin_phone=\u00a0\u00bb|0px||\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb custom_padding=\u00a0\u00bb6px|0px|6px|0px|true|true\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset4&Prime; box_shadow_horizontal=\u00a0\u00bb0px\u00a0\u00bb box_shadow_vertical=\u00a0\u00bb1px\u00a0\u00bb box_shadow_color=\u00a0\u00bb#000000&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][et_pb_button button_text=\u00a0\u00bb\u00c9v\u00e9nements d&apos;aujourd&apos;hui\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_bg_color=\u00a0\u00bbrgba(0,0,0,0)\u00a0\u00bb button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_font=\u00a0\u00bb|700|||||||\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px|0px||\u00a0\u00bb custom_margin_phone=\u00a0\u00bb|0px||\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb custom_padding=\u00a0\u00bb6px|0px|6px|0px|true|true\u00a0\u00bb box_shadow_style=\u00a0\u00bbpreset4&Prime; box_shadow_horizontal=\u00a0\u00bb0px\u00a0\u00bb box_shadow_vertical=\u00a0\u00bb1px\u00a0\u00bb box_shadow_color=\u00a0\u00bb#000000&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb12px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb link_font=\u00a0\u00bb||||on||||\u00a0\u00bb link_text_color=\u00a0\u00bb#666666&Prime; header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_text_align=\u00a0\u00bbleft\u00a0\u00bb header_2_font=\u00a0\u00bb||||||||\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb12px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb5px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.8em\u00a0\u00bb max_width_tablet=\u00a0\u00bb70%\u00a0\u00bb max_width_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Suivre<\/h3>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=\u00a0\u00bb4.16&Prime; custom_margin=\u00a0\u00bb-20px|||-10px\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb\u00a0\u00bb custom_margin_phone=\u00a0\u00bb-20px||\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb filter_invert=\u00a0\u00bb100%\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb icon_color__hover=\u00a0\u00bb#e02b20&Prime;][et_pb_social_media_follow_network social_network=\u00a0\u00bbfacebook\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00a0\u00bbtwitter\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]twitter[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00a0\u00bbgoogle-plus\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]google-plus[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00a0\u00bbinstagram\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb follow_button=\u00a0\u00bboff\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.16&Prime; text_font=\u00a0\u00bb||||||||\u00a0\u00bb text_font_size=\u00a0\u00bb12px\u00a0\u00bb text_line_height=\u00a0\u00bb2em\u00a0\u00bb link_font=\u00a0\u00bb||||on||||\u00a0\u00bb link_text_color=\u00a0\u00bb#666666&Prime; header_font=\u00a0\u00bb||||||||\u00a0\u00bb header_text_align=\u00a0\u00bbleft\u00a0\u00bb header_3_font=\u00a0\u00bb|700||on|||||\u00a0\u00bb header_3_font_size=\u00a0\u00bb12px\u00a0\u00bb header_3_letter_spacing=\u00a0\u00bb5px\u00a0\u00bb header_3_line_height=\u00a0\u00bb1.8em\u00a0\u00bb max_width_tablet=\u00a0\u00bb70%\u00a0\u00bb max_width_last_edited=\u00a0\u00bboff|phone\u00a0\u00bb header_3_font_size_tablet=\u00a0\u00bb\u00a0\u00bb header_3_font_size_phone=\u00a0\u00bb\u00a0\u00bb header_3_font_size_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Suscr\u00edbete<\/h3>\n<p>[\/et_pb_text][et_pb_signup mailchimp_list=\u00a0\u00bbSlavaET|11a914d1cc\u00a0\u00bb first_name_field=\u00a0\u00bboff\u00a0\u00bb last_name_field=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; form_field_background_color=\u00a0\u00bb#f3f3f4&Prime; form_field_custom_padding=\u00a0\u00bb12px||12px||true\u00a0\u00bb header_font=\u00a0\u00bb|||on|||||\u00a0\u00bb header_font_size=\u00a0\u00bb14px\u00a0\u00bb header_letter_spacing=\u00a0\u00bb5px\u00a0\u00bb header_line_height=\u00a0\u00bb1.8em\u00a0\u00bb form_field_font=\u00a0\u00bb||||||||\u00a0\u00bb form_field_font_size=\u00a0\u00bb14px\u00a0\u00bb use_background_color=\u00a0\u00bboff\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb14px\u00a0\u00bb button_text_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_bg_color=\u00a0\u00bb#000000&Prime; button_border_width=\u00a0\u00bb0px\u00a0\u00bb button_border_radius=\u00a0\u00bb0px\u00a0\u00bb button_font=\u00a0\u00bb|700|||||||\u00a0\u00bb button_custom_padding=\u00a0\u00bb12px||12px||true\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb custom_margin=\u00a0\u00bb-39px||\u00a0\u00bb border_radii_fields=\u00a0\u00bbon|0px|0px|0px|0px\u00a0\u00bb locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_signup][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9claration de l&rsquo;artiste Walter E. SanchezJe consacre ma vie \u00e0 cultiver ma sensibilit\u00e9, \u00e0 apprendre \u00e0 percevoir le subtil, \u00e0 \u00e9couter le profond et \u00e0 ressentir ce qui se cache au-del\u00e0 des formes. Mon art est le reflet de ce cheminement : un espace o\u00f9 la couleur, la texture et la vibration se transforment en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1336","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9claration de l&#039;artiste - Artwes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wsfreespirit.com\/fr\/artist-statement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9claration de l&#039;artiste - Artwes\" \/>\n<meta property=\"og:description\" content=\"D\u00e9claration de l&#039;artiste Walter E. SanchezJe consacre ma vie \u00e0 cultiver ma sensibilit\u00e9, \u00e0 apprendre \u00e0 percevoir le subtil, \u00e0 \u00e9couter le profond et \u00e0 ressentir ce qui se cache au-del\u00e0 des formes. Mon art est le reflet de ce cheminement : un espace o\u00f9 la couleur, la texture et la vibration se transforment en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wsfreespirit.com\/fr\/artist-statement\/\" \/>\n<meta property=\"og:site_name\" content=\"Artwes\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-17T19:16:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wsfreespirit.com\\\/fr\\\/artist-statement\\\/\",\"url\":\"https:\\\/\\\/wsfreespirit.com\\\/fr\\\/artist-statement\\\/\",\"name\":\"D\u00e9claration de l'artiste - Artwes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wsfreespirit.com\\\/#website\"},\"datePublished\":\"2023-11-21T00:14:59+00:00\",\"dateModified\":\"2026-02-17T19:16:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wsfreespirit.com\\\/fr\\\/artist-statement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wsfreespirit.com\\\/fr\\\/artist-statement\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wsfreespirit.com\\\/fr\\\/artist-statement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wsfreespirit.com\\\/fr\\\/about-me\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9claration de l&rsquo;artiste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wsfreespirit.com\\\/#website\",\"url\":\"https:\\\/\\\/wsfreespirit.com\\\/\",\"name\":\"Artwes\",\"description\":\"Artist Page By Walter E. Sanchez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wsfreespirit.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9claration de l'artiste - Artwes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wsfreespirit.com\/fr\/artist-statement\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9claration de l'artiste - Artwes","og_description":"D\u00e9claration de l'artiste Walter E. SanchezJe consacre ma vie \u00e0 cultiver ma sensibilit\u00e9, \u00e0 apprendre \u00e0 percevoir le subtil, \u00e0 \u00e9couter le profond et \u00e0 ressentir ce qui se cache au-del\u00e0 des formes. Mon art est le reflet de ce cheminement : un espace o\u00f9 la couleur, la texture et la vibration se transforment en [&hellip;]","og_url":"https:\/\/wsfreespirit.com\/fr\/artist-statement\/","og_site_name":"Artwes","article_modified_time":"2026-02-17T19:16:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wsfreespirit.com\/fr\/artist-statement\/","url":"https:\/\/wsfreespirit.com\/fr\/artist-statement\/","name":"D\u00e9claration de l'artiste - Artwes","isPartOf":{"@id":"https:\/\/wsfreespirit.com\/#website"},"datePublished":"2023-11-21T00:14:59+00:00","dateModified":"2026-02-17T19:16:09+00:00","breadcrumb":{"@id":"https:\/\/wsfreespirit.com\/fr\/artist-statement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wsfreespirit.com\/fr\/artist-statement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wsfreespirit.com\/fr\/artist-statement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wsfreespirit.com\/fr\/about-me\/"},{"@type":"ListItem","position":2,"name":"D\u00e9claration de l&rsquo;artiste"}]},{"@type":"WebSite","@id":"https:\/\/wsfreespirit.com\/#website","url":"https:\/\/wsfreespirit.com\/","name":"Artwes","description":"Artist Page By Walter E. Sanchez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wsfreespirit.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wsfreespirit.com\/fr\/wp-json\/wp\/v2\/pages\/1336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wsfreespirit.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wsfreespirit.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wsfreespirit.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wsfreespirit.com\/fr\/wp-json\/wp\/v2\/comments?post=1336"}],"version-history":[{"count":4,"href":"https:\/\/wsfreespirit.com\/fr\/wp-json\/wp\/v2\/pages\/1336\/revisions"}],"predecessor-version":[{"id":1366,"href":"https:\/\/wsfreespirit.com\/fr\/wp-json\/wp\/v2\/pages\/1336\/revisions\/1366"}],"wp:attachment":[{"href":"https:\/\/wsfreespirit.com\/fr\/wp-json\/wp\/v2\/media?parent=1336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}